{"id":761,"date":"2026-01-14T15:01:39","date_gmt":"2026-01-14T14:01:39","guid":{"rendered":"https:\/\/www.apic.bzh\/?p=761"},"modified":"2026-01-15T16:18:15","modified_gmt":"2026-01-15T15:18:15","slug":"soiree-apic-des-echanges-interessants-et-eclairants","status":"publish","type":"post","link":"https:\/\/www.apic.bzh\/index.php\/2026\/01\/14\/soiree-apic-des-echanges-interessants-et-eclairants\/","title":{"rendered":"Soir\u00e9e APIC : des \u00e9changes int\u00e9ressants et \u00e9clairants !"},"content":{"rendered":"\n<p>Mardi 13 janvier, la soir\u00e9e autour des th\u00e8mes de comment faire mieux \u00e0 Plabennec a r\u00e9uni 90 participants \u00e0 la salle Marcel Bouguen !<\/p>\n\n\n\n<p>Les habitants se sont r\u00e9unis pour \u00e9changer autour de 3 questions :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Vos enfants sont-ils \u00e9panouis \u00e0 Plabennec, et vous ?<\/li>\n\n\n\n<li>Vous d\u00e9placez-vous facilement dans et depuis Plabennec ?<\/li>\n\n\n\n<li>Vous sentez-vous en s\u00e9curit\u00e9 dans votre commune ?<\/li>\n<\/ul>\n\n\n\n<p>Les discussions ont \u00e9t\u00e9 int\u00e9ressantes et \u00e9clairantes sur les id\u00e9es et projets \u00e0 porter. <\/p>\n\n\n\n<p>Merci pour votre pr\u00e9sence, vos constats et propositions !<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"763\" src=\"https:\/\/www.apic.bzh\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-14-at-11.14.00-1-768x1024.jpeg\" alt=\"\" class=\"wp-image-763\" srcset=\"https:\/\/www.apic.bzh\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-14-at-11.14.00-1-768x1024.jpeg 768w, https:\/\/www.apic.bzh\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-14-at-11.14.00-1-225x300.jpeg 225w, https:\/\/www.apic.bzh\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-14-at-11.14.00-1-1152x1536.jpeg 1152w, https:\/\/www.apic.bzh\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-14-at-11.14.00-1-810x1080.jpeg 810w, https:\/\/www.apic.bzh\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-14-at-11.14.00-1.jpeg 1200w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"774\" src=\"https:\/\/www.apic.bzh\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-13-at-23.37.48-1-1-1024x768.jpeg\" alt=\"\" class=\"wp-image-774\" srcset=\"https:\/\/www.apic.bzh\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-13-at-23.37.48-1-1-1024x768.jpeg 1024w, https:\/\/www.apic.bzh\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-13-at-23.37.48-1-1-300x225.jpeg 300w, https:\/\/www.apic.bzh\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-13-at-23.37.48-1-1-768x576.jpeg 768w, https:\/\/www.apic.bzh\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-13-at-23.37.48-1-1-1536x1152.jpeg 1536w, https:\/\/www.apic.bzh\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-13-at-23.37.48-1-1-1440x1080.jpeg 1440w, https:\/\/www.apic.bzh\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-13-at-23.37.48-1-1.jpeg 2000w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"768\" src=\"https:\/\/www.apic.bzh\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-13-at-23.37.48-1-1024x768.jpeg\" alt=\"\" class=\"wp-image-768\" srcset=\"https:\/\/www.apic.bzh\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-13-at-23.37.48-1-1024x768.jpeg 1024w, https:\/\/www.apic.bzh\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-13-at-23.37.48-1-300x225.jpeg 300w, https:\/\/www.apic.bzh\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-13-at-23.37.48-1-768x576.jpeg 768w, https:\/\/www.apic.bzh\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-13-at-23.37.48-1-1536x1152.jpeg 1536w, https:\/\/www.apic.bzh\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-13-at-23.37.48-1-1440x1080.jpeg 1440w, https:\/\/www.apic.bzh\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-13-at-23.37.48-1.jpeg 2000w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mardi 13 janvier, la soir\u00e9e autour des th\u00e8mes de comment faire mieux \u00e0 Plabennec a r\u00e9uni 90 participants \u00e0 la salle Marcel Bouguen ! Les habitants se sont r\u00e9unis pour [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":762,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"saved_in_kubio":false,"footnotes":""},"categories":[16],"tags":[],"class_list":["post-761","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites"],"_links":{"self":[{"href":"https:\/\/www.apic.bzh\/index.php\/wp-json\/wp\/v2\/posts\/761","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.apic.bzh\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.apic.bzh\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.apic.bzh\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.apic.bzh\/index.php\/wp-json\/wp\/v2\/comments?post=761"}],"version-history":[{"count":3,"href":"https:\/\/www.apic.bzh\/index.php\/wp-json\/wp\/v2\/posts\/761\/revisions"}],"predecessor-version":[{"id":776,"href":"https:\/\/www.apic.bzh\/index.php\/wp-json\/wp\/v2\/posts\/761\/revisions\/776"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.apic.bzh\/index.php\/wp-json\/wp\/v2\/media\/762"}],"wp:attachment":[{"href":"https:\/\/www.apic.bzh\/index.php\/wp-json\/wp\/v2\/media?parent=761"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.apic.bzh\/index.php\/wp-json\/wp\/v2\/categories?post=761"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.apic.bzh\/index.php\/wp-json\/wp\/v2\/tags?post=761"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}